{"id":413,"count":3,"description":"","link":"https:\/\/ncservo.com\/.wp-toolkit_m\/brand\/hauhinco\/","name":"HAUHINCO","slug":"hauhinco","taxonomy":"product_brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HAUHINCO Archives - Nc Servo Technology<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HAUHINCO Archives - Nc Servo Technology\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ncservo.com\/.wp-toolkit_m\/brand\/hauhinco\/\" \/>\n<meta property=\"og:site_name\" content=\"Nc Servo Technology\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ncservo.com\/.wp-toolkit_m\/wp-content\/uploads\/2018\/10\/logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"419\" \/>\n\t<meta property=\"og:image:height\" content=\"154\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NcServo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/brand\\\/hauhinco\\\/\",\"url\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/brand\\\/hauhinco\\\/\",\"name\":\"HAUHINCO Archives - Nc Servo Technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/brand\\\/hauhinco\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/brand\\\/hauhinco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HAUHINCO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/#website\",\"url\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/\",\"name\":\"NC Servo Technology\",\"description\":\"We Buy &amp; Repair Servo Valves\",\"publisher\":{\"@id\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/#organization\",\"name\":\"NC Servo\",\"url\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"NC Servo\"},\"image\":{\"@id\":\"https:\\\/\\\/ncservo.com\\\/.wp-toolkit_m\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NCServo\\\/\",\"https:\\\/\\\/x.com\\\/NcServo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HAUHINCO Archives - Nc Servo Technology","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"HAUHINCO Archives - Nc Servo Technology","og_url":"https:\/\/ncservo.com\/.wp-toolkit_m\/brand\/hauhinco\/","og_site_name":"Nc Servo Technology","og_image":[{"width":419,"height":154,"url":"https:\/\/ncservo.com\/.wp-toolkit_m\/wp-content\/uploads\/2018\/10\/logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@NcServo","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ncservo.com\/.wp-toolkit_m\/brand\/hauhinco\/","url":"https:\/\/ncservo.com\/.wp-toolkit_m\/brand\/hauhinco\/","name":"HAUHINCO Archives - Nc Servo Technology","isPartOf":{"@id":"https:\/\/ncservo.com\/.wp-toolkit_m\/#website"},"breadcrumb":{"@id":"https:\/\/ncservo.com\/.wp-toolkit_m\/brand\/hauhinco\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ncservo.com\/.wp-toolkit_m\/brand\/hauhinco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ncservo.com\/.wp-toolkit_m\/"},{"@type":"ListItem","position":2,"name":"HAUHINCO"}]},{"@type":"WebSite","@id":"https:\/\/ncservo.com\/.wp-toolkit_m\/#website","url":"https:\/\/ncservo.com\/.wp-toolkit_m\/","name":"NC Servo Technology","description":"We Buy &amp; Repair Servo Valves","publisher":{"@id":"https:\/\/ncservo.com\/.wp-toolkit_m\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ncservo.com\/.wp-toolkit_m\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ncservo.com\/.wp-toolkit_m\/#organization","name":"NC Servo","url":"https:\/\/ncservo.com\/.wp-toolkit_m\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ncservo.com\/.wp-toolkit_m\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"NC Servo"},"image":{"@id":"https:\/\/ncservo.com\/.wp-toolkit_m\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NCServo\/","https:\/\/x.com\/NcServo"]}]}},"_links":{"self":[{"href":"https:\/\/ncservo.com\/.wp-toolkit_m\/wp-json\/wp\/v2\/product_brand\/413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ncservo.com\/.wp-toolkit_m\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/ncservo.com\/.wp-toolkit_m\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/ncservo.com\/.wp-toolkit_m\/wp-json\/wp\/v2\/product?product_brand=413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}